{"id":2853,"date":"2025-01-22T08:49:55","date_gmt":"2025-01-22T08:49:55","guid":{"rendered":"https:\/\/ayh-pt.dev.loba.com\/contacte-nos\/"},"modified":"2025-03-12T17:01:44","modified_gmt":"2025-03-12T17:01:44","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"<!-- Bloco T\u00edtulo -->\n<div class=\"title-block\">\n  <div class=\"container-fluid\">\n    <div class=\"row \">\n      <div class=\"col-12 offset-xl-1 col-xl-10\">\n        <div class=\"subtitle\">Talk to us<\/div>\n      <\/div>\n      <div class=\"col-12 offset-xl-1 col-xxl-3 col-xl-4 col-lg-5\">\n        <h1> <!-- Pode ser h1 ou h2 -->\n          Contact us        <\/h1> <!-- \/ Pode ser h1 ou h2 -->\n      <\/div>\n      <div class=\"offset-xxl-3 offset-xl-2 col-xl-4 offset-lg-1 col-lg-6\">\n        <div class=\"title-block__text\">\n          <p>Would you like to learn more about our work or start a new project? <strong>Let us Architect Your Home<\/strong>.<\/p>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/div>\n\n<!-- Bloco imagem com ou sem anima\u00e7\u00e3o - se a cliente escolher adicionar uma anima\u00e7\u00e3o a este bloco adicionar a classe image-animation -->\n    <div class=\"image-block-wide \">\n        <img decoding=\"async\" src=\"https:\/\/ayh-pt.dev.loba.com\/app\/uploads\/2025\/01\/image-block.jpg\" alt=\"Espa\u00e7o da Architect Your Home.\">\n    <\/div>\n\n\n<!-- Bloco formul\u00e1rio -->\n<div class=\"form-block\">\n    <div class=\"container-fluid\">\n        <div class=\"row\">\n            <div class=\"col-12 offset-xl-1 col-xl-10\">\n                \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3091-o1\" lang=\"pt-PT\" dir=\"ltr\" data-wpcf7-id=\"3091\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/2853#wpcf7-f3091-o1\" method=\"post\" class=\"wpcf7-form init needs-validation modal-contact\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"3091\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pt_PT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3091-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n    <div class=\"col-lg-6\">\n        <div class=\"row\">\n            <div class=\"col-lg-6\">\n                <div class=\"form-group\">\n                    <label class=\"form-label\">Name<\/label>\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"modal-first-name\" \/><\/span>\n                <\/div>\n            <\/div>\n            <div class=\"col-lg-6\">\n                <div class=\"form-group\">\n                    <label class=\"form-label\">Surname<\/label>\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"modal-last-name\" \/><\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-6\">\n        <div class=\"form-group\">\n            <label class=\"form-label\">How did you hear about us?<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-how\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"modal-how\" \/><\/span>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"row\">\n    <div class=\"col-lg-6\">\n        <div class=\"form-group with-icon with-icon__email\">\n            <label>Email<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"modal-email\" \/><\/span>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-6\">\n        <div class=\"form-group\">\n            <label>Type of project<\/label>\n            <div class=\"custom-select-option\">\n                <select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" name=\"project-type\"><option value=\"Select the type of project\">Select the type of project<\/option><option value=\"Residential\">Residential<\/option><option value=\"Investments\">Investments<\/option><option value=\"Hotels\">Hotels<\/option><option value=\"Decoration\">Decoration<\/option><\/select>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"row\">\n    <div class=\"col-lg-6\">\n        <div class=\"form-group with-icon with-icon__phone\">\n            <label>Phone<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"modal-phone\" \/><\/span>\n        <\/div>\n        <div class=\"form-group with-icon with-icon__local\">\n            <label>Project location<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-local\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"modal-local\" \/><\/span>\n        <\/div>\n        <div class=\"form-group with-icon with-icon__cpostal\">\n            <label>Postal Code<\/label>\n            <div class=\"row\">\n                <div class=\"col-6\">\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-cpostal\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"modal-cpostal\" \/><\/span>\n                <\/div>\n                <div class=\"col-6\">\n                    <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-cpostal2\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control cpostal2\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"modal-cpostal2\" \/><\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-6\">\n        <div class=\"form-group form-group--textarea\">\n            <label>Brief project description<\/label>\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-message\"><textarea cols=\"40\" rows=\"6\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" name=\"modal-message\"><\/textarea><\/span>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"row\">\n    <div class=\"col-lg-6\">\n        <div class=\"form-check\">\n            <span class=\"wpcf7-form-control-wrap\" data-name=\"modal-terms\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"modal-terms\" value=\"1\" class=\"form-check-input\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">By submitting your data, you are giving us permission to use the information to assist you and contact you. Don&#8217;t worry, you can request the deletion of your data at any time.<\/span><\/label><\/span><\/span><\/span>\n        <\/div>\n    <\/div>\n    <div class=\"col-lg-6\">\n        <button class=\"wpcf7-form-control wpcf7-submit has-spinner btn btn-primary\" type=\"submit\" \/>Submit<\/button><\/button>\n    <\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-canvas.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-2853","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact Us - Architect Your Home<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us - Architect Your Home\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Architect Your Home\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-12T17:01:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/\",\"url\":\"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/\",\"name\":\"Contact Us - Architect Your Home\",\"isPartOf\":{\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/#website\"},\"datePublished\":\"2025-01-22T08:49:55+00:00\",\"dateModified\":\"2025-03-12T17:01:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ayh-pt.dev.loba.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/#website\",\"url\":\"https:\/\/ayh-pt.dev.loba.com\/en\/\",\"name\":\"Architect Your Home\",\"description\":\"Even if it\u2019s more than a home, let us architect your home.\",\"publisher\":{\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ayh-pt.dev.loba.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/#organization\",\"name\":\"Architect Your Home\",\"url\":\"https:\/\/ayh-pt.dev.loba.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ayh-pt.dev.loba.com\/app\/uploads\/2025\/01\/logo-white.svg\",\"contentUrl\":\"https:\/\/ayh-pt.dev.loba.com\/app\/uploads\/2025\/01\/logo-white.svg\",\"width\":150,\"height\":40,\"caption\":\"Architect Your Home\"},\"image\":{\"@id\":\"https:\/\/ayh-pt.dev.loba.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact Us - Architect Your Home","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/","og_locale":"en_US","og_type":"article","og_title":"Contact Us - Architect Your Home","og_url":"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/","og_site_name":"Architect Your Home","article_modified_time":"2025-03-12T17:01:44+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/","url":"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/","name":"Contact Us - Architect Your Home","isPartOf":{"@id":"https:\/\/ayh-pt.dev.loba.com\/en\/#website"},"datePublished":"2025-01-22T08:49:55+00:00","dateModified":"2025-03-12T17:01:44+00:00","breadcrumb":{"@id":"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ayh-pt.dev.loba.com\/en\/contact-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ayh-pt.dev.loba.com\/en\/"},{"@type":"ListItem","position":2,"name":"Contact Us"}]},{"@type":"WebSite","@id":"https:\/\/ayh-pt.dev.loba.com\/en\/#website","url":"https:\/\/ayh-pt.dev.loba.com\/en\/","name":"Architect Your Home","description":"Even if it\u2019s more than a home, let us architect your home.","publisher":{"@id":"https:\/\/ayh-pt.dev.loba.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ayh-pt.dev.loba.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ayh-pt.dev.loba.com\/en\/#organization","name":"Architect Your Home","url":"https:\/\/ayh-pt.dev.loba.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ayh-pt.dev.loba.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ayh-pt.dev.loba.com\/app\/uploads\/2025\/01\/logo-white.svg","contentUrl":"https:\/\/ayh-pt.dev.loba.com\/app\/uploads\/2025\/01\/logo-white.svg","width":150,"height":40,"caption":"Architect Your Home"},"image":{"@id":"https:\/\/ayh-pt.dev.loba.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ayh-pt.dev.loba.com\/en\/wp-json\/wp\/v2\/pages\/2853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ayh-pt.dev.loba.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ayh-pt.dev.loba.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ayh-pt.dev.loba.com\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/ayh-pt.dev.loba.com\/en\/wp-json\/wp\/v2\/comments?post=2853"}],"version-history":[{"count":4,"href":"https:\/\/ayh-pt.dev.loba.com\/en\/wp-json\/wp\/v2\/pages\/2853\/revisions"}],"predecessor-version":[{"id":3148,"href":"https:\/\/ayh-pt.dev.loba.com\/en\/wp-json\/wp\/v2\/pages\/2853\/revisions\/3148"}],"wp:attachment":[{"href":"https:\/\/ayh-pt.dev.loba.com\/en\/wp-json\/wp\/v2\/media?parent=2853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}